{"id":2205,"date":"2023-07-20T17:15:12","date_gmt":"2023-07-20T17:15:12","guid":{"rendered":"https:\/\/hotelpejo.it\/armonia-rooms\/"},"modified":"2026-06-15T13:16:05","modified_gmt":"2026-06-15T13:16:05","slug":"pokoje-armonia","status":"publish","type":"page","link":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/","title":{"rendered":"Pokoje Armonia"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1324&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1316&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_left=&#8221;5%&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f7f5f3&#8243; bg_image=&#8221;1571&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;opacity-background&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;10%&#8221; bottom_padding=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;NOWY WYMIAR GO\u015aCINNO\u015aCI&#8221; font_container=&#8221;tag:h6|font_size:18px|text_align:center|color:%23726357|line_height:25px&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Pokoje Armonia&#8221; font_container=&#8221;tag:h2|font_size:77px|text_align:center|color:%23726357|line_height:90px&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;accent-color&#8221; custom_height=&#8221;80&#8243;][vc_column_text css=&#8221;.vc_custom_1689873081196{padding-top: 40px !important;}&#8221;]Witamy w naszych ekskluzywnych pokojach Armonia, miejscu, w kt\u00f3rym komfort spotyka si\u0119 z wyj\u0105tkowym wzornictwem. To propozycja stworzona dla os\u00f3b ceni\u0105cych pi\u0119kno detali. Ka\u017cdy pok\u00f3j zosta\u0142 urz\u0105dzony z pasj\u0105 i dba\u0142o\u015bci\u0105 o najmniejsze szczeg\u00f3\u0142y, aby stworzy\u0107 eleganck\u0105 i wyrafinowan\u0105 przestrze\u0144. Pozw\u00f3l otuli\u0107 si\u0119 atmosferze relaksu, w kt\u00f3rej elegancja harmonijnie \u0142\u0105czy si\u0119 z wygod\u0105. Pokoje Armonia to idealne schronienie dla tych, kt\u00f3rzy marz\u0105 o niezapomnianym pobycie w otoczeniu perfekcyjnie dopracowanych detali.[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;Zarezerwuj pok\u00f3j&#8221; url=&#8221;https:\/\/www.simplebooking.it\/ibe\/search?hid=5407&#038;lang=PL&#038;cur=EUR#\/q&#8221; margin_top=&#8221;40&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][image_with_animation image_url=&#8221;1344&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;10px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;12%&#8221;][vc_gallery type=&#8221;flickity_static_height_style&#8221; images=&#8221;2211,2212,2213,2214,2215,2216,2217,2218,2219,2220,2221,2222,2223,2224&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;609&#215;342&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; right_padding_desktop=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;center&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Apartament Armonia Spa&#8221; id=&#8221;1751383673433-10&#8243; tab_id=&#8221;1751383673434-1&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Apartament Armonia Spa<br \/>\n(37 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Apartamenty SPA s\u0105 prawdziw\u0105 per\u0142\u0105 naszego hotelu. Nowoczesne i eleganckie, zosta\u0142y zaprojektowane z my\u015bl\u0105 o go\u015bciach poszukuj\u0105cych wyrafinowanego stylu oraz najwy\u017cszego komfortu. Przestronne wn\u0119trza zach\u0119caj\u0105 do odpoczynku i celebrowania chwil dobrego samopoczucia a\u017c do wieczora, najbardziej romantycznej pory dnia, kiedy niebo przybiera zachwycaj\u0105ce barwy. Dzi\u0119ki prywatnej strefie wellness mo\u017cesz cieszy\u0107 si\u0119 kompleksowym do\u015bwiadczeniem relaksu i regeneracji.<\/p>\n<p>Mo\u017cesz te\u017c podarowa\u0107 sobie wyj\u0105tkowy rytua\u0142 wellness, korzystaj\u0105c z odpr\u0119\u017caj\u0105cej k\u0105pieli w wannie z hydromasa\u017cem, koj\u0105cego prysznica mgie\u0142kowego oraz regeneruj\u0105cej sauny. Nast\u0119pnie wystarczy zanurzy\u0107 si\u0119 w mi\u0119kko\u015bci \u0142\u00f3\u017cka King Size w rozmiarze 180&#215;200 cm marki 'Simmons Natural Heritage&#8217; o wysoko\u015bci 28 cm. Zosta\u0142o ono zaprojektowane zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonane z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek nabiera zupe\u0142nie nowego wymiaru.<\/p>\n<p>Do dyspozycji naszych go\u015bci pozostaje r\u00f3wnie\u017c k\u0105cik z przek\u0105skami, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych oraz minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a. Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2237,2238,2239,2240,2241,2242,2243&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;full&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Junior Apartament Armonia Spa&#8221; id=&#8221;1751383673481-8&#8243; tab_id=&#8221;1751383673481-2&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Apartament Junior Armonia Spa<br \/>\n(31 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Apartamenty SPA Junior Suite s\u0105 prawdziw\u0105 per\u0142\u0105 naszego hotelu. Nowoczesne i eleganckie, zosta\u0142y zaprojektowane z dba\u0142o\u015bci\u0105 o ka\u017cdy detal, aby przywita\u0107 go\u015bci w wyrafinowanym i stylowym otoczeniu. Przestronne wn\u0119trza zach\u0119caj\u0105 do marze\u0144 i celebrowania chwil pe\u0142nych relaksu a\u017c do wieczora, najbardziej romantycznej pory dnia, kiedy niebo przybiera zachwycaj\u0105ce i niepowtarzalne barwy. Dzi\u0119ki prywatnej strefie wellness mo\u017cesz cieszy\u0107 si\u0119 kompleksowym do\u015bwiadczeniem relaksu i regeneracji.<\/p>\n<p>Podaruj sobie wyj\u0105tkowy rytua\u0142 wellness, korzystaj\u0105c z odpr\u0119\u017caj\u0105cej k\u0105pieli w wannie z hydromasa\u017cem, koj\u0105cego prysznica mgie\u0142kowego oraz regeneruj\u0105cej sauny. Nast\u0119pnie mo\u017cesz zanurzy\u0107 si\u0119 w mi\u0119kko\u015bci \u0142\u00f3\u017cka King Size w rozmiarze 180&#215;200 cm marki 'Simmons Natural Heritage&#8217; o wysoko\u015bci 28 cm. Zosta\u0142o ono zaprojektowane zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonane z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w wype\u0142niaj\u0105cych. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek staje si\u0119 prawdziw\u0105 przyjemno\u015bci\u0105. Tutaj relaks jest najwa\u017cniejszy.<\/p>\n<p>Do dyspozycji go\u015bci pozostaje r\u00f3wnie\u017c k\u0105cik z przek\u0105skami, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych oraz minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a.<\/p>\n<p>Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2244,2245,2246,2247,2248,2249,2250&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Apartament z saun\u0105&#8221; id=&#8221;1751383673515-0&#8243; tab_id=&#8221;1751383673515-2&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Apartament z saun\u0105<br \/>\n(37 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Apartamenty z saun\u0105 s\u0105 nowoczesne i eleganckie. Ka\u017cdy detal zosta\u0142 starannie dopracowany, aby przywita\u0107 go\u015bci w wyrafinowanym stylu i stworzy\u0107 atmosfer\u0119 sprzyjaj\u0105c\u0105 relaksowi oraz pe\u0142nemu odpr\u0119\u017ceniu.<\/p>\n<p>Mo\u017cesz podarowa\u0107 sobie wyj\u0105tkowe chwile relaksu wellness, korzystaj\u0105c z regeneruj\u0105cej sauny na podczerwie\u0144, a nast\u0119pnie zanurzy\u0107 si\u0119 w mi\u0119kko\u015bci \u0142\u00f3\u017cka King Size w rozmiarze 180&#215;200 cm marki 'Simmons Natural Heritage&#8217; o wysoko\u015bci 28 cm. Zosta\u0142o ono zaprojektowane zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonane z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w wype\u0142niaj\u0105cych. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek staje si\u0119 prawdziw\u0105 przyjemno\u015bci\u0105. Tutaj relaks jest najwa\u017cniejszy. W cz\u0119\u015bci wypoczynkowej znajduje si\u0119 r\u00f3wnie\u017c rozk\u0142adana sofa z dwoma pojedynczymi miejscami do spania oraz k\u0105cik z przek\u0105skami, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych i minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a.<\/p>\n<p>Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2225,2226,2227,2228,2229,2230,2231,2232,2233,2234,2235,2236&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Junior Apartament z saun\u0105&#8221; id=&#8221;1751383673549-7&#8243; tab_id=&#8221;1751383673549-5&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Apartament Junior z saun\u0105<br \/>\n(25 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Apartamenty Junior z saun\u0105 s\u0105 nowoczesne i eleganckie. Ka\u017cdy detal zosta\u0142 starannie dopracowany, aby przywita\u0107 go\u015bci w wyrafinowanym stylu i stworzy\u0107 atmosfer\u0119 sprzyjaj\u0105c\u0105 relaksowi oraz pe\u0142nemu odpr\u0119\u017ceniu.<\/p>\n<p>Do dyspozycji go\u015bci pozostaje r\u00f3wnie\u017c k\u0105cik z przek\u0105skami, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych oraz minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>Mo\u017cesz podarowa\u0107 sobie wyj\u0105tkowe chwile relaksu wellness, korzystaj\u0105c z regeneruj\u0105cej sauny na podczerwie\u0144, a nast\u0119pnie zanurzy\u0107 si\u0119 w mi\u0119kko\u015bci \u0142\u00f3\u017cka marki 'Simmons Natural Heritage&#8217; w rozmiarze 180&#215;200 cm i wysoko\u015bci 28 cm. Zosta\u0142o ono zaprojektowane zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonane z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w wype\u0142niaj\u0105cych. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek staje si\u0119 prawdziw\u0105 przyjemno\u015bci\u0105. Tutaj relaks jest najwa\u017cniejszy!<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a.<\/p>\n<p>Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2251,2252,2253,2254,2255,2256,2257,2258,2259&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Przestronny pok\u00f3j Deluxe&#8221; id=&#8221;1751383673593-1&#8243; tab_id=&#8221;1751383673593-4&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Przestronny pok\u00f3j Deluxe<br \/>\n(27 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Dba\u0142o\u015b\u0107 o detale, komfort i wyj\u0105tkowy design definiuj\u0105 pok\u00f3j nasz przestronny pok\u00f3j Deluxe, kt\u00f3ry zachwyca eleganckimi wn\u0119trzami oraz atmosfer\u0105 sprzyjaj\u0105c\u0105 relaksowi. Szczeg\u00f3lnego uroku dodaje romantyczny 'k\u0105cik przytulania&#8217;, stworzony z my\u015bl\u0105 o chwilach sp\u0119dzanych we dwoje.<\/p>\n<p>Do dyspozycji go\u015bci pozostaje r\u00f3wnie\u017c strefa przek\u0105sek, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych oraz minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>Centralnym elementem pokoju jest przestronne \u0142\u00f3\u017cko dwuosobowe King Size z materacem marki 'Simmons Natural Heritage&#8217; w rozmiarze 180&#215;200 cm i wysoko\u015bci 28 cm. Zosta\u0142o ono zaprojektowane zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonane z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w wype\u0142niaj\u0105cych. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek staje si\u0119 prawdziw\u0105 przyjemno\u015bci\u0105. Tutaj relaks jest najwa\u017cniejszy!<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a. Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2267,2260,2261,2262,2263,2264,2265,2266&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Pok\u00f3j Armonia Deluxe&#8221; id=&#8221;1751383673617-1&#8243; tab_id=&#8221;1751383673617-9&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Pok\u00f3j Armonia Deluxe<br \/>\n(22,5 m\u00b2)&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Dba\u0142o\u015b\u0107 o detale, komfort i wyj\u0105tkowy design definiuj\u0105 pok\u00f3j Armonia Deluxe, kt\u00f3ry zachwyca eleganckimi wn\u0119trzami i atmosfer\u0105 sprzyjaj\u0105c\u0105 relaksowi.<\/p>\n<p>Do dyspozycji go\u015bci pozostaje r\u00f3wnie\u017c k\u0105cik z przek\u0105skami, niewielka przestrze\u0144 wyposa\u017cona w wyb\u00f3r herbat zio\u0142owych oraz minibar, idealna na przyjemn\u0105 przerw\u0119 w ci\u0105gu dnia.<\/p>\n<p>Centralnym elementem pokoju jest przestronne \u0142\u00f3\u017cko dwuosobowe King Size z materacem marki 'Simmons Natural Heritage&#8217; w rozmiarze 180&#215;200 cm i wysoko\u015bci 28 cm. Zosta\u0142 on zaprojektowany zgodnie z ide\u0105 zr\u00f3wnowa\u017conego rozwoju i wykonany z wysokiej jako\u015bci, przyjaznych \u015brodowisku materia\u0142\u00f3w wype\u0142niaj\u0105cych. Ca\u0142o\u015b\u0107 dope\u0142niaj\u0105 wygodne poduszki i otulaj\u0105ce ko\u0142dry, dzi\u0119ki kt\u00f3rym odpoczynek staje si\u0119 prawdziw\u0105 przyjemno\u015bci\u0105. Tutaj relaks jest najwa\u017cniejszy!<\/p>\n<p>W komfortowej \u0142azience z oknem znajdziesz mi\u0119kkie szlafroki, kapcie, suszark\u0119 do w\u0142os\u00f3w oraz wysokiej jako\u015bci kosmetyki do piel\u0119gnacji cia\u0142a. Wyposa\u017cenie pokoju dope\u0142niaj\u0105 drewniane pod\u0142ogi, telewizor 40 cali, bezp\u0142atne Wi-Fi oraz sejf mieszcz\u0105cy tablet lub laptop.<\/p>\n<p>W pokojach tego typu obowi\u0105zuje zakaz palenia. Zwierz\u0119ta nie s\u0105 akceptowane.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2272,2273,2274,2268,2269,2270,2271&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;2&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;none&#8221;][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;jumbo&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;Zarezerwuj pok\u00f3j&#8221; url=&#8221;https:\/\/www.simplebooking.it\/ibe2\/hotel\/5407\/?lang=PL&#038;cur=EUR&#8221; margin_top=&#8221;40&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f7f5f3&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;10%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;107&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_blank&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;hotel_pejo_icona&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; column_link=&#8221;https:\/\/www.simplebooking.it\/ibe\/search?hid=5407&#038;lang=PL&#038;cur=EUR&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;150px&#8221;][vc_custom_heading text=&#8221;Zarezerwuj pok\u00f3j&#8221; font_container=&#8221;tag:h4|text_align:center|color:%231d3638&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1677158314596{margin-bottom: 20px !important;}&#8221; link=&#8221;url:https%3A%2F%2Fwww.simplebooking.it%2Fibe%2Fsearch%3Fhid%3D5407%26lang%3DPL%26cur%3DEUR|target:_blank&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;150px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Obserwuj nas w mediach spo\u0142eczno\u015bciowych&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1669750312893{margin-bottom: 20px !important;}&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-facebook-square&#8221; url=&#8221;https:\/\/www.facebook.com\/hotelpejo\/&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;0px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-instagram&#8221; margin_left=&#8221;20px&#8221; url=&#8221;https:\/\/www.instagram.com\/hotelpejo\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1669750350396{margin-bottom: 60px !important;}&#8221;]\n<h5 style=\"text-align: center;\">Zainspiruj si\u0119 <em>natur\u0105<\/em><\/h5>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1324&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2205","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pokoje Armonia - Hotel Pejo<\/title>\n<meta name=\"description\" content=\"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pokoje Armonia - Hotel Pejo\" \/>\n<meta property=\"og:description\" content=\"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Pejo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T13:16:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/pokoje-armonia\\\/\",\"url\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/pokoje-armonia\\\/\",\"name\":\"Pokoje Armonia - Hotel Pejo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/#website\"},\"datePublished\":\"2023-07-20T17:15:12+00:00\",\"dateModified\":\"2026-06-15T13:16:05+00:00\",\"description\":\"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/pokoje-armonia\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/pokoje-armonia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/pokoje-armonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pokoje Armonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/\",\"name\":\"Hotel Pejo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotelpejo.it\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pokoje Armonia - Hotel Pejo","description":"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/","og_locale":"pl_PL","og_type":"article","og_title":"Pokoje Armonia - Hotel Pejo","og_description":"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.","og_url":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/","og_site_name":"Hotel Pejo","article_modified_time":"2026-06-15T13:16:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"7 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/","url":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/","name":"Pokoje Armonia - Hotel Pejo","isPartOf":{"@id":"https:\/\/hotelpejo.it\/pl\/#website"},"datePublished":"2023-07-20T17:15:12+00:00","dateModified":"2026-06-15T13:16:05+00:00","description":"Odkryj ekskluzywne Pokoje Armonia w Hotel Pejo \u2013 elegancki design, strefa wellness i widok na g\u00f3ry w sercu Val di Pejo.","breadcrumb":{"@id":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotelpejo.it\/pl\/pokoje-armonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelpejo.it\/pl\/"},{"@type":"ListItem","position":2,"name":"Pokoje Armonia"}]},{"@type":"WebSite","@id":"https:\/\/hotelpejo.it\/pl\/#website","url":"https:\/\/hotelpejo.it\/pl\/","name":"Hotel Pejo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelpejo.it\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/pages\/2205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/comments?post=2205"}],"version-history":[{"count":3,"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/pages\/2205\/revisions"}],"predecessor-version":[{"id":2276,"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/pages\/2205\/revisions\/2276"}],"wp:attachment":[{"href":"https:\/\/hotelpejo.it\/pl\/wp-json\/wp\/v2\/media?parent=2205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}